{"id":2382,"date":"2018-05-14T15:40:22","date_gmt":"2018-05-14T13:40:22","guid":{"rendered":"https:\/\/protec-windows-always-again.com\/?page_id=2382"},"modified":"2021-01-28T16:09:46","modified_gmt":"2021-01-28T15:09:46","slug":"cookie-rechtlinien","status":"publish","type":"page","link":"https:\/\/protec-windows-always-again.com\/de\/cookie-rechtlinien\/","title":{"rendered":"Cookie Rechtlinien"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Diese Cookie-Richtlinie wurde zuletzt am 10\/05\/2026 aktualisiert und gilt f\u00fcr B\u00fcrger und Einwohner mit st\u00e4ndigem Wohnsitz im Europ\u00e4ischen Wirtschaftsraum und der Schweiz.<\/i><br><\/p><h2>1. Einf\u00fchrung<\/h2><p>Unsere Website, <a href=\"https:\/\/protec-windows-always-again.com\/de\/\">https:\/\/protec-windows-always-again.com\/de\/<\/a> (im folgenden: \"Die Website\") verwendet Cookies und \u00e4hnliche Technologien (der Einfachheit halber werden all diese unter \"Cookies\" zusammengefasst). Cookies werden au\u00dferdem von uns beauftragten Drittparteien platziert. In dem unten stehendem Dokument informieren wir dich \u00fcber die Verwendung von Cookies auf unserer Website.<\/p><h2>2. Was sind Cookies?<\/h2><p>Ein Cookie ist eine einfache kleine Datei, die gemeinsam mit den Seiten einer Internetadresse versendet und vom Webbrowser auf dem PC oder einem anderen Ger\u00e4t gespeichert werden kann. Die darin gespeicherten Informationen k\u00f6nnen w\u00e4hrend folgender Besuche zu unseren oder den Servern relevanter Drittanbieter gesendet werden.<\/p><h2>3. Was sind Skripte?<\/h2><p>Ein Script ist ein St\u00fcck Programmcode, das benutzt wird, um unserer Website Funktionalit\u00e4t und Interaktivit\u00e4t zu erm\u00f6glichen. Dieser Code wird auf unseren Servern oder auf deinem Ger\u00e4t ausgef\u00fchrt.<\/p><h2>4. Was ist ein Web Beacon?<\/h2><p>Ein Web-Beacon (auch Pixel-Tag genannt), ist ein kleines unsichtbares Textfragment oder Bild auf einer Website, das benutzt wird, um den Verkehr auf der Website zu \u00fcberwachen. Um dies zu erm\u00f6glichen werden diverse Daten von dir mittels Web-Beacons gespeichert.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Technische oder funktionelle Cookies<\/p><p>Einige Cookies stellen sicher, dass Teile unserer Website richtig funktionieren und deine Nutzervorlieben bekannt bleiben. Durch das Platzieren funktionaler Cookies machen wir es dir einfacher unsere Website zu besuchen. Auf diese Weise musst du bei Besuchen unserer Website nicht wiederholt die gleichen Informationen eingeben, oder deine Gegenst\u00e4nde bleiben beispielsweise in deinem Warenkorb bis du bezahlst. Wir k\u00f6nnen diese Cookies ohne dein Einverst\u00e4ndnis platzieren.<\/p><p class=\"cmplz-subtitle\">5.2 Analytische Cookies<\/p><p>Wir verwenden analytische Cookies, um das Website-Erlebnis f\u00fcr unsere Nutzer zu optimieren. Mit diesen analytischen Cookies erhalten wir Einblicke in die Nutzung unserer Website.&nbsp;Wir bitten um deine Erlaubnis, analytische Cookies zu setzen.<\/p><p class=\"cmplz-subtitle\">5.3 Marketing- \/ Tracking-Cookies<\/p><p>Marketing- \/ Tracking-Cookies sind Cookies oder eine andere Form der lokalen Speicherung, die zur Erstellung von Benutzerprofilen verwendet werden, um Werbung anzuzeigen oder den Benutzer auf dieser Website oder \u00fcber mehrere Websites hinweg f\u00fcr \u00e4hnliche Marketingzwecke zu verfolgen.<\/p><p class=\"cmplz-subtitle\">5.4 Soziale-Medien<\/p><p>Auf unserer Website haben wir Inhalte von Facebook und Instagram eingebunden, um Webseiten zu bewerben (z. B. \"Gef\u00e4llt mir\", \"Pin\") oder zu teilen (z. B. \"Tweet\") in sozialen Netzwerken wie Facebook und Instagram. Dieser Inhalt ist mit einem Code eingebettet, der von Facebook und Instagram stammt und Cookies platziert. Diese Inhalte k\u00f6nnen bestimmte Informationen f\u00fcr personalisierte Werbung speichern und verarbeiten.<\/p><p>Bitte lies die Datenschutzerkl\u00e4rung dieser sozialen Netzwerke (die sich regelm\u00e4\u00dfig \u00e4ndern kann), um zu erfahren, wie sie mit deinen (pers\u00f6nlichen) Daten umgehen, die sie mithilfe dieser Cookies verarbeiten. Die abgerufenen Daten werden so weit wie m\u00f6glich anonymisiert. Facebook und Instagram hat seine Sitze in den Vereinigten Staaten<\/p><h2>6. Platzierte Cookies<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>GDPR Cookie Consent<\/h3>\n\t\t<p>Gegenstand der Untersuchung<\/p>\n\t\t<label for=\"cmplz_service_gdpr-cookie-consent\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service gdpr-cookie-consent<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_gdpr-cookie-consent\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"gdpr-cookie-consent\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p>Wir verwenden GDPR Cookie Consent f\u00fcr Verwaltung der Cookie-Einwilligung. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/gdpr-cookie-consent\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Gegenstand der Untersuchung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/gdpr-cookie-consent\/gdprallowed_cookies\/\">gdpr[allowed_cookies<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/gdpr-cookie-consent\/gdprconsent_types\/\">gdpr[consent_types<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Statistik (anonym)<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p>Wir verwenden Google Analytics f\u00fcr Website-Statistik. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-analytics\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Analytics Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistik (anonym)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga\/\">_ga<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">2 Jahre<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Z\u00e4hlt und verfolgt Seitenaufrufe<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_gid\/\">_gid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Tag<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Z\u00e4hlt und verfolgt Seitenaufrufe<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_gat\/\">_gat<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Min<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Filter requests from bots<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>funktionelle, Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p>Wir verwenden WordPress f\u00fcr Website-Entwicklung. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>funktionelle<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">nichts<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">\u00fcberpr\u00fcft, ob Cookies gesetzt werden k\u00f6nnen<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_0fccad09e111918db6363377b39bc8af\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Determina si el usuario ha iniciado sesi\u00f3n<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>funktionelle<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p>Wir verwenden WPML f\u00fcr Verwaltung der Gebietsschemen. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wpml\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>funktionelle<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wpml\/wp-wpml_current_language\/\">wp-wpml_current_language<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Tag<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Spracheinstellungen<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>GDPR Cookie Compliance<\/h3>\n\t\t<p>Gegenstand der Untersuchung<\/p>\n\t\t<label for=\"cmplz_service_gdpr-cookie-compliance\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service gdpr-cookie-compliance<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_gdpr-cookie-compliance\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"gdpr-cookie-compliance\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p>Wir verwenden GDPR Cookie Compliance f\u00fcr Verwaltung der Cookie-Einwilligung. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/gdpr-cookie-compliance\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Gegenstand der Untersuchung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/gdpr-cookie-compliance\/gdpr\/\">gdpr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Marketing\/Verfolgung<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p>Wir verwenden Google Fonts f\u00fcr Anzeige von Webfonts. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Fonts Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing\/Verfolgung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-fonts\/tcb_google_fonts\/\">Google Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">nichts<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Fordere die Benutzer-IP-Adresse an<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Marketing\/Verfolgung<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p>Wir verwenden Google reCAPTCHA f\u00fcr Spam-Vorbeugung. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-recaptcha\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google reCAPTCHA Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing\/Verfolgung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcc\/\">rc::c<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Filter requests from bots<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcb\/\">rc::b<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Filter requests from bots<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rca\/\">rc::a<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">hartn\u00e4ckig<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Filter requests from bots<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Estad\u00edsticas (an\u00f3nimas), Statistik<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p>Wir verwenden YouTube f\u00fcr Video-Display. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">YouTube Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas (an\u00f3nimas)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">GPS<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 minuto<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Filtrar solicitudes de bots<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">VISITOR_INFO1_LIVE<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 minuto<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Filtrar solicitudes de bots<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistik<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/ysc\/\">YSC<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere die eindeutige User-ID<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/pref\/\">PREF<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Verfolge Besucher quer \u00fcber Websiten<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Facebook<\/h3>\n\t\t<p>Marketing\/Verfolgung, funktionelle<\/p>\n\t\t<label for=\"cmplz_service_facebook\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service facebook<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_facebook\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"facebook\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p>Wir verwenden Facebook f\u00fcr Anzeige der letzten Social-Posts und\/oder Social-Share-Buttons. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/facebook\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/policy\/cookies\">Facebook Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing\/Verfolgung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/actppresence-2\/\">actppresence<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Verwalte die H\u00e4ufigkeit der angezeigten Werbung<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbc\/\">_fbc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">2 Jahre<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Store last visit<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fbm_\/\">fbm*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Benutzer-Details<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/xs\/\">xs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">3 Monate<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Store a unique session ID<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fr\/\">fr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">3 Monate<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Enable ad delivery or retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbp\/\">_fbp<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">3 Monate<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Verfolge Besucher quer \u00fcber Websiten<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/datr\/\">datr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">2 Jahre<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Beuge Betrug vor<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/sb\/\">sb<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">2 Jahre<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Browser-Angaben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbm_\/\">*_fbm_<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Benutzer-Details<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>funktionelle<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/wd\/\">wd<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Woche<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Festlegung der Bildschirmaufl\u00f6sung<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/act\/\">act<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">90 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Benutzer eingeloggt lassen<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/c_user\/\">c_user<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">90 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere die eindeutige User-ID<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/csm\/\">csm<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">90 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Beuge Betrug vor<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/actppresence\/\">presence<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Store and track if the browser tab is active<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Sonstiges<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_sonstiges\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service sonstiges<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sonstiges\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"sonstiges\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Die Weitergabe von Daten wird noch untersucht<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Gegenstand der Untersuchung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">displayCookieConsent<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_choice<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics-anonymous<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">trdipcktrffcext<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">extCacheFunc<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_lscache_vary<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">i18nextLng<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">rank-math-option-sitemap-index<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Determina si el usuario ha iniciado sesi\u00f3n<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">rank-math-option-titles-index<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Determina si el usuario ha iniciado sesi\u00f3n<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wpr-hash<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Determina si el usuario ha iniciado sesi\u00f3n<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_grecaptcha<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Determina si el usuario ha iniciado sesi\u00f3n<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">rank-math-option-search-index<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Determina si el usuario ha iniciado sesi\u00f3n<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">rank-math-option-general-index<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Determina si el usuario ha iniciado sesi\u00f3n<\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Zustimmung<\/h2><p>Wenn du unsere Website das erste Mal besuchst, zeigen wir dir ein Pop-Up mit einer Erkl\u00e4rung \u00fcber Cookies. Sobald du auf \u201eEinstellungen speichern\u201c klickst, gibst du uns dein Einverst\u00e4ndnis, alle von dir gew\u00e4hlten Kategorien von Cookies und Plugins wie in dieser Cookie-Erkl\u00e4rung beschrieben zu verwenden. Du kannst die Verwendung von Cookies \u00fcber deinen Browser deaktivieren, aber bitte beachte, dass unsere Website dann unter Umst\u00e4nden nicht richtig funktioniert.<\/p><p class=\"cmplz-subtitle\">7.1 Verwalte deine Zustimmungseinstellungen<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Du hast die Cookie-Richtlinie ohne Javascript-Unterst\u00fctzung geladen.&nbsp;Unter AMP kannst du die Schaltfl\u00e4che zum Zustimmen der Einwilligung unten auf der Seite verwenden.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Aktivierung\/Deaktivierung und L\u00f6schen von Cookies<\/h2><p>Du kannst deinen Internetbrowser verwenden um automatisch oder manuell Cookies zu l\u00f6schen. Du kannst au\u00dferdem spezifizieren ob spezielle Cookies nicht platziert werden sollen. Eine andere M\u00f6glichkeit ist es deinen  Internetbrowser derart einzurichten, dass du jedes Mal benachrichtigt wirst, wenn ein Cookie platziert wird. F\u00fcr weitere Information \u00fcber diese M\u00f6glichkeiten beachte die Anweisungen in der Hilfesektion deines Browsers.<\/p><p>Bitte nimm zur Kenntnis, dass unsere Website m\u00f6glicherweise nicht richtig funktioniert, wenn alle Cookies deaktiviert sind. Wenn du die Cookies in deinem Browser l\u00f6scht, werden diese neu platziert, wenn du unsere Website erneut besuchst.<\/p><h2>9. Deine Rechte in Bezug auf pers\u00f6nliche Daten<\/h2><p>Du hast in Bezug auf deine pers\u00f6nlichen Daten die folgenden Rechte:<\/p><ul>\n                    <li>Du hast das Recht zu wissen, warum deine pers\u00f6nlichen Daten gebraucht werden, was mit ihnen passiert und wie lange diese verwahrt werden.<\/li>\n                    <li>Zugriffsrecht: Du hast das Recht deine uns bekannten pers\u00f6nliche Daten einzusehen.<\/li>\n                    <li>Recht auf Berichtigung: Du hast das Recht wann immer du w\u00fcnscht, deine pers\u00f6nlichen Daten zu erg\u00e4nzen, zu korrigieren sowie gel\u00f6scht oder blockiert zu bekommen.<\/li>\n                    <li>Wenn du uns dein Einverst\u00e4ndnis zur Verarbeitung deiner Daten gegeben hast, hast du das Recht dieses Einverst\u00e4ndnis zu widerrufen und deine pers\u00f6nlichen Daten l\u00f6schen zu lassen.<\/li>\n                    <li>Recht auf Datentransfer deiner Daten: Du hast das Recht, alle deine pers\u00f6nlichen Daten von einem Kontrolleur anzufordern und in ihrer Gesamtheit zu einem anderen Kontrolleur zu transferieren.<\/li>\n                    <li>Widerspruchsrecht: Du kannst der Verarbeitung deiner Daten widersprechen. Wir entsprechen dem, es sei denn es gibt berechtigte Gr\u00fcnde f\u00fcr die Verarbeitung.<\/li>\n                <\/ul><p>Um diese Rechte auszu\u00fcben kontaktiere uns bitte. Bitte beziehe dich auf die Kontaktdaten am Ende dieser Cookie-Erkl\u00e4rung. Wenn du eine Beschwerde dar\u00fcber hast, wie wir deine Daten behandeln, w\u00fcrden wir diese gerne h\u00f6ren, aber du hast auch das Recht diese an die Aufsichtsbeh\u00f6rde (Datenschutzbeh\u00f6rde) zu richten.<\/p><h2>10. Kontaktdaten<\/h2><p>F\u00fcr Fragen und\/oder Kommentare \u00fcber unsere Cookie-Richtlinien und diese Aussage kontaktiere uns bitte mittels der folgenden Kontaktdaten:<\/p><p><span class=\"cmplz-contact-organisation\">C-TEC PRO-TEC GROUP SPAIN, S.L.<\/span><br>\n                      <span class=\"cmplz-contact-address\">Camino Pera De Agua 81-104, Pol\u00edgono Industrial Los Perales, Buz\u00f3n 15, 29651 Mijas (M\u00e1laga)<\/span><br>\n                      <span class=\"cmplz-contact-country\">Spanien<\/span><br>\n                    Website: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/protec-windows-always-again.com\/de\/\">https:\/\/protec-windows-always-again.com\/de\/<\/a><\/span><br>\n                    E-Mail: <span class=\"cmplz-contact-email\">&#105;&#110;&#102;o&#064;gru&#112;&#111;-&#112;&#114;o&#116;ec&#046;&#099;om<\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Phone number: +34 952 587 573<\/span><\/p><p>Diese Cookie-Richtlinie wurde mit <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\" rel=\"noopener\">cookiedatabase.org<\/a> am 28\/01\/2021 synchronisiert.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2382","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/protec-windows-always-again.com\/de\/wp-json\/wp\/v2\/pages\/2382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protec-windows-always-again.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/protec-windows-always-again.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/protec-windows-always-again.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/protec-windows-always-again.com\/de\/wp-json\/wp\/v2\/comments?post=2382"}],"version-history":[{"count":2,"href":"https:\/\/protec-windows-always-again.com\/de\/wp-json\/wp\/v2\/pages\/2382\/revisions"}],"predecessor-version":[{"id":31481,"href":"https:\/\/protec-windows-always-again.com\/de\/wp-json\/wp\/v2\/pages\/2382\/revisions\/31481"}],"wp:attachment":[{"href":"https:\/\/protec-windows-always-again.com\/de\/wp-json\/wp\/v2\/media?parent=2382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}